{"id":14581,"date":"2023-09-19T14:00:00","date_gmt":"2023-09-19T17:00:00","guid":{"rendered":"https:\/\/revidigital.ielusc.br\/?p=14581"},"modified":"2023-09-19T14:23:11","modified_gmt":"2023-09-19T17:23:11","slug":"a-rotina-alimentar-de-estudantes-universitarios-pesquisa-aponta-que-um-terco-esta-com-niveis-de-sobrepeso-ou-obesidade","status":"publish","type":"post","link":"https:\/\/revidigital.ielusc.br\/index.php\/2023\/09\/19\/a-rotina-alimentar-de-estudantes-universitarios-pesquisa-aponta-que-um-terco-esta-com-niveis-de-sobrepeso-ou-obesidade\/","title":{"rendered":"A rotina alimentar de estudantes universit\u00e1rios: pesquisa aponta que um ter\u00e7o est\u00e1 com n\u00edveis de sobrepeso ou obesidade\u00a0"},"content":{"rendered":"\n<p>Estar em um curso superior pode exigir muito dos jovens. Frequentar as aulas, acompanhar todos os conte\u00fados e, por muitas vezes, gerenciar tudo isso com uma jornada de trabalho di\u00e1ria. Essa \u00e9 a realidade da maioria dos universit\u00e1rios: fazer malabares com o tempo \u00e9 quase uma parte essencial no processo de gradua\u00e7\u00e3o. Por\u00e9m, ser\u00e1 que entre todas as tarefas, o ato mais simples de se alimentar, est\u00e1 na lista de prioridades dos jovens?<\/p>\n\n\n\n<p>Certamente, comer faz parte da rotina dos jovens, mas ser\u00e1 que a pressa do dia a dia vem afetando a qualidade das refei\u00e7\u00f5es? <a href=\"http:\/\/www.univates.br\/revistas\/index.php\/destaques\/article\/view\/2651\">Um estudo feito em uma faculdade de Caxias do Sul,<\/a> no Rio Grande do Sul, em 2020, aponta que a maioria dos estudantes evitam o consumo de alimentos ultraprocessados e raramente acabam substituindo refei\u00e7\u00f5es, por lanches r\u00e1pidos. E mesmo que 94% dos entrevistados estivessem em boa situa\u00e7\u00e3o nutricional, cerca de um ter\u00e7o dos entrevistados apresentavam em seu n\u00famero de IMC (\u00cdndice de Massa Corporal), algum grau de sobrepeso ou obesidade.<\/p>\n\n\n\n<p>A coordenadora do curso de nutri\u00e7\u00e3o da Faculdade IELUSC, professora doutora Marilyn Gon\u00e7alves, diz que em um quadro geral, a maioria da popula\u00e7\u00e3o apresenta certo grau de sobrepeso. Por\u00e9m \u201ca falta de tempo do estudante, prejudica e muito sua alimenta\u00e7\u00e3o\u201d. Marilyn ainda diz que os ditos \u201cgrupos de risco\u201d como os estudantes, apresentam maiores n\u00fameros de incid\u00eancias.&nbsp;<\/p>\n\n\n\n<p>Em outro <a href=\"https:\/\/ojs.unifor.br\/RBPS\/article\/view\/8510\/pdf\">estudo, feito pela Universidade Tr\u00e1s-os-Montes e Alto Douro<\/a>, de Portugal, os n\u00fameros s\u00e3o similares aos do estudo feito no Brasil. Os n\u00fameros mostram que as universit\u00e1rias do sexo feminino tem maior incid\u00eancia dos casos de sobrepeso ou obesidado, tendo 51% de incid\u00eancia. \u201cAs mulheres t\u00eam menos tempo para cuidar da alimenta\u00e7\u00e3o. Elas, muitas vezes t\u00eam mais responsabilidades al\u00e9m das aulas. Algumas trabalham e t\u00eam filhos para cuidar. S\u00f3 isso as deixam mais expostas,\u201d observa a professora Marilyn.<\/p>\n\n\n\n<p>Ao ser questionada sobre a possibilidade de haver algo a se fazer para contornar a situa\u00e7\u00e3o alimentar dos estudantes, a professora diz que uma estrat\u00e9gia multidisciplinar deve ser tra\u00e7ada. Segundo ela, juntando os conhecimentos de outros cursos para que a cantina da faculdade possa come\u00e7ar a servir comunidades de melhor qualidade por um pre\u00e7o acess\u00edvel, pode ser um grande passo para uma melhor alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em um question\u00e1rio feito por alunos do curso de jornalismo da Faculdade Ielusc, 27,9% dos acad\u00eamicos questionados n\u00e3o possuem h\u00e1bitos de alimenta\u00e7\u00e3o saud\u00e1vel. Na institui\u00e7\u00e3o, 47,5% dos acad\u00eamicos costumam levar um lanche. Destes, 23% costumam levar chocolates, p\u00e3es, bolachas recheadas, salgadinhos e refrigerantes, como comida.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Rotina alimentar de estudantes universit\u00e1rios\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/Q-YUIqwVEmo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Estar em um curso superior pode exigir muito dos jovens. Frequentar as aulas, acompanhar todos os conte\u00fados e, por muitas vezes, gerenciar tudo isso com uma jornada de trabalho di\u00e1ria. Essa \u00e9 a realidade da maioria dos universit\u00e1rios: fazer malabares com o tempo \u00e9 quase uma parte essencial no processo de gradua\u00e7\u00e3o. Por\u00e9m, ser\u00e1 que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97,17],"tags":[1780,1577,18,1781],"_links":{"self":[{"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/posts\/14581"}],"collection":[{"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/comments?post=14581"}],"version-history":[{"count":1,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/posts\/14581\/revisions"}],"predecessor-version":[{"id":14582,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/posts\/14581\/revisions\/14582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/media\/14592"}],"wp:attachment":[{"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/media?parent=14581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/categories?post=14581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revidigital.ielusc.br\/index.php\/wp-json\/wp\/v2\/tags?post=14581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}